{"id":13838,"date":"2025-03-31T10:24:05","date_gmt":"2025-03-31T08:24:05","guid":{"rendered":"https:\/\/casale.ch\/sluzby\/"},"modified":"2025-11-06T15:37:43","modified_gmt":"2025-11-06T14:37:43","slug":"sluzby","status":"publish","type":"page","link":"https:\/\/casale.ch\/cs\/sluzby\/","title":{"rendered":"Slu\u017eby"},"content":{"rendered":"[vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_image=&#8220;2785&#8243; bg_position=&#8220;center center&#8220; background_image_loading=&#8220;default&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; bottom_margin=&#8220;20px&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;capabilities&#8220; id=&#8220;section_hero_categoria_primo&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css_animation=&#8220;fadeInUp&#8220; css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h1>Slu\u017eby<\/h1>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; equal_height=&#8220;yes&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#f8f8f8&#8243; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;servizi&#8220; id=&#8220;section_hero_categoria_primo_bottom&#8220; disable_element=&#8220;yes&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; el_class=&#8220;box_grigio&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][vc_column_text css_animation=&#8220;none&#8220; css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h2 style=\"margin-bottom: 20px; font-size: 30px;\"><strong>Slu\u017eby \u0161it\u00e9 na m\u00edru pro ka\u017ed\u00fd z\u00e1vod a&nbsp;ka\u017ed\u00e9 za\u0159\u00edzen\u00ed<\/strong><\/h2>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;servizi&#8220; id=&#8220;section_page_menu&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][page_submenu alignment=&#8220;left&#8220; link_color=&#8220;#e3602c&#8220;][page_link link_url=&#8220;#plant_engineering_services&#8220; title=&#8220;Technick\u00e9 slu\u017eby pro z\u00e1vody&#8220; id=&#8220;1758797984877-5&#8243; tab_id=&#8220;1758797984878-5&#8243;] [\/page_link][page_link link_url=&#8220;#plant_operation_support&#8220; title=&#8220;Provozn\u00ed podpora z\u00e1vodu&#8220; id=&#8220;1758797984941-9&#8243; tab_id=&#8220;1758797984942-8&#8243;] [\/page_link][page_link title=&#8220;Digit\u00e1ln\u00ed a&amp;nbsp;diagnostick\u00e1 \u0159e\u0161en\u00ed&#8220; id=&#8220;1758797984970-5&#8243; link_url=&#8220;#digital_diagnostic_solutions&#8220; tab_id=&#8220;1758797984971-4&#8243;][\/page_link][\/page_submenu][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;sezione_servizio&#8220; id=&#8220;plant_engineering_services&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;5\/12&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_raw_html css=&#8220;&#8220;]W3dwY29kZSBpZD0iNzg2MCIgdGFnX3NsdWc9InNlcnZpY2VzX21hY2hpbmVyeXNlcnZpY2VzIl0=[\/vc_raw_html][image_with_animation image_url=&#8220;12131&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220;][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;7\/12&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][nectar_highlighted_text color_type=&#8220;regular&#8220; text_color=&#8220;#cc0f4d&#8220; style=&#8220;full_text&#8220; highlight_expansion=&#8220;default&#8220; text_direction=&#8220;default&#8220;]\n<h2 class=\"big_h1\">Technick\u00e9 slu\u017eby pro z\u00e1vody<\/h2>\n[\/nectar_highlighted_text][nectar_highlighted_text color_type=&#8220;regular&#8220; text_color=&#8220;#cc0f4d&#8220; style=&#8220;full_text&#8220; highlight_expansion=&#8220;default&#8220; text_direction=&#8220;default&#8220;]\n<h3>Slu\u017eby a&nbsp;produkty pro zv\u00fd\u0161en\u00ed spolehlivosti, prodlou\u017een\u00ed provozn\u00ed \u017eivotnosti a&nbsp;optimalizaci v\u00fdkonu z\u00e1vodu<\/h3>\n[\/nectar_highlighted_text][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220; el_class=&#8220;descrizione&#8220;]Na\u0161e nab\u00eddka slu\u017eeb pokr\u00fdv\u00e1 cel\u00fd \u017eivotn\u00ed cyklus z\u00e1vod\u016f na v\u00fdrobu chemik\u00e1li\u00ed a&nbsp;hnojiv&nbsp;\u2013 od po\u010d\u00e1te\u010dn\u00edch in\u017een\u00fdrsk\u00fdch posouzen\u00ed a\u017e po dlouhodobou optimalizaci v\u00fdkonu a&nbsp;renovaci za\u0159\u00edzen\u00ed. A\u0165 u\u017e jde o&nbsp;technologie Casale, nebo syst\u00e9my od jin\u00fdch v\u00fdznamn\u00fdch poskytovatel\u016f licenc\u00ed anebo spole\u010dnost\u00ed EPC, na\u0161e specializovan\u00e9 t\u00fdmy poskytuj\u00ed prvot\u0159\u00eddn\u00ed podporu d\u00edky kombinaci technick\u00fdch znalost\u00ed, provozn\u00edch zku\u0161enost\u00ed a&nbsp;p\u0159\u00edstupu orientovan\u00e9ho na hled\u00e1n\u00ed \u0159e\u0161en\u00ed. D\u00edky flexibiln\u00edmu a&nbsp;partnersk\u00e9mu p\u0159\u00edstupu pom\u00e1h\u00e1me klient\u016fm zv\u00fd\u0161it spolehlivost provozu, prodlou\u017eit \u017eivotnost za\u0159\u00edzen\u00ed a&nbsp;dosahovat trval\u00e9ho zlep\u0161ov\u00e1n\u00ed v\u00fdkonu.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;sezione_servizio&#8220; id=&#8220;plant_engineering_services_pt2&#8243; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220; el_class=&#8220;descrizione&#8220;]\n<h3>Stroj\u00edrensk\u00e9 slu\u017eby<\/h3>\n<ul>\n<li>Hodnocen\u00ed v\u00fdkonu kritick\u00fdch rota\u010dn\u00edch za\u0159\u00edzen\u00ed (kompresory, \u010derpadla a&nbsp;turb\u00edny)<\/li>\n<li>V\u00fdm\u011bna nebo modernizace kritick\u00fdch rota\u010dn\u00edch za\u0159\u00edzen\u00ed, v\u010detn\u011b modernizace souvisej\u00edc\u00edch \u0159\u00eddic\u00edch a&nbsp;ochrann\u00fdch syst\u00e9m\u016f.<\/li>\n<li>Anal\u00fdza poruch<\/li>\n<li>Dynamick\u00e1 anal\u00fdza puls\u016f a&nbsp;vibrac\u00ed<\/li>\n<li>N\u00e1vrh a&nbsp;dod\u00e1vky kritick\u00e9ho za\u0159\u00edzen\u00ed<\/li>\n<\/ul>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220; el_class=&#8220;descrizione&#8220;]\n<h3>N\u00e1stroje<\/h3>\n<ul>\n<li>P\u0159ezkum\/zlep\u0161en\u00ed \u0159\u00eddic\u00edch syst\u00e9m\u016f DCS a&nbsp;ESD<\/li>\n<li>N\u00e1vrh a&nbsp;po\u0159\u00edzen\u00ed kritick\u00fdch p\u0159\u00edstroj\u016f, inteligentn\u00ed p\u0159\u00edstroje a&nbsp;regula\u010dn\u00ed ventily<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220; el_class=&#8220;descrizione&#8220;]\n<h3>Potrub\u00ed<\/h3>\n<ul>\n<li>Laserov\u00e9 skenov\u00e1n\u00ed<\/li>\n<li>3D&nbsp;modely<\/li>\n<li>Anal\u00fdza nap\u011bt\u00ed<\/li>\n<li>Anal\u00fdza selh\u00e1n\u00ed<\/li>\n<\/ul>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220; el_class=&#8220;descrizione&#8220;]\n<h3>Stavebn\u00ed a&nbsp;konstruk\u010dn\u00ed<\/h3>\n<ul>\n<li>Kontrola\/n\u00e1vrh z\u00e1klad\u016f, reg\u00e1l\u016f, ocelov\u00fdch konstrukc\u00ed atd.<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;reverse sezione_servizio&#8220; id=&#8220;plant_operation_support&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;5\/12&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_raw_html css=&#8220;&#8220;]W3dwY29kZSBpZD0iNzg2MCIgdGFnX3NsdWc9InNlcnZpY2VzX2RpZ2l0YWxzZXJ2aWNlcyJd[\/vc_raw_html][image_with_animation image_url=&#8220;200&#8243; image_size=&#8220;medium_featured&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220;][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;7\/12&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][nectar_highlighted_text color_type=&#8220;regular&#8220; text_color=&#8220;#cc0f4d&#8220; style=&#8220;full_text&#8220; highlight_expansion=&#8220;default&#8220; text_direction=&#8220;default&#8220;]\n<h2 class=\"big_h1\">Provozn\u00ed podpora z\u00e1vodu<\/h2>\n[\/nectar_highlighted_text][nectar_highlighted_text color_type=&#8220;regular&#8220; text_color=&#8220;#cc0f4d&#8220; style=&#8220;full_text&#8220; highlight_expansion=&#8220;default&#8220; text_direction=&#8220;default&#8220;]\n<h3 class=\"big_h1\">Udr\u017een\u00ed v\u00fdkonu i&nbsp;po uveden\u00ed do provozu<\/h3>\n[\/nectar_highlighted_text][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]Spole\u010dnost Casale podporuje sv\u00e9 klienty b\u011bhem cel\u00e9ho provozn\u00edho cyklu jejich z\u00e1vod\u016f a&nbsp;zaji\u0161\u0165uje stabiln\u00ed, efektivn\u00ed a&nbsp;bezpe\u010dn\u00fd chod od spu\u0161t\u011bn\u00ed a\u017e po dlouhodob\u00fd provoz. N\u00e1\u0161 t\u00fdm poskytuje odbornou podporu p\u0159i uv\u00e1d\u011bn\u00ed za\u0159\u00edzen\u00ed do provozu, \u0161kolen\u00ed obsluhy, vzd\u00e1len\u00e9m monitorov\u00e1n\u00ed a&nbsp;\u0159e\u0161en\u00ed provozn\u00edch probl\u00e9m\u016f. A\u0165 u\u017e jde o&nbsp;spu\u0161t\u011bn\u00ed nov\u00e9ho z\u00e1vodu, nebo o&nbsp;optimalizaci st\u00e1vaj\u00edc\u00edho provozu, poskytujeme c\u00edlenou podporu, kter\u00e1 zajist\u00ed, \u017ee va\u0161e za\u0159\u00edzen\u00ed bude fungovat na \u0161pi\u010dkov\u00e9 \u00farovni&nbsp;\u2013 dnes i&nbsp;v&nbsp;budoucnu.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;sezione_servizio&#8220; id=&#8220;digital_diagnostic_solutions&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;5\/12&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_raw_html css=&#8220;&#8220;]W3dwY29kZSBpZD0iNzg2MCIgdGFnX3NsdWc9InNlcnZpY2VzX2RpYWdub3N0aWN0ZXN0aW5nIl0=[\/vc_raw_html][image_with_animation image_url=&#8220;12131&#8243; image_size=&#8220;medium_featured&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220;][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;7\/12&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][nectar_highlighted_text color_type=&#8220;regular&#8220; text_color=&#8220;#cc0f4d&#8220; style=&#8220;full_text&#8220; highlight_expansion=&#8220;default&#8220; text_direction=&#8220;default&#8220;]\n<h2 class=\"big_h1\">Digit\u00e1ln\u00ed a&nbsp;diagnostick\u00e1 \u0159e\u0161en\u00ed<\/h2>\n[\/nectar_highlighted_text][nectar_highlighted_text color_type=&#8220;regular&#8220; text_color=&#8220;#cc0f4d&#8220; style=&#8220;full_text&#8220; highlight_expansion=&#8220;default&#8220; text_direction=&#8220;default&#8220;]\n<h3 class=\"big_h1\">Zvy\u0161ov\u00e1n\u00ed v\u00fdkonu pomoc\u00ed dat<\/h3>\n[\/nectar_highlighted_text][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220; el_class=&#8220;descrizione&#8220;]Digit\u00e1ln\u00ed a&nbsp;diagnostick\u00e9 slu\u017eby spole\u010dnosti Casale prom\u011b\u0148uj\u00ed surov\u00e1 data ze z\u00e1vodu v&nbsp;prakticky vyu\u017eiteln\u00e9 poznatky. Pomoc\u00ed pokro\u010dil\u00e9 analytiky, vlastn\u00edch simula\u010dn\u00edch n\u00e1stroj\u016f a&nbsp;monitorov\u00e1n\u00ed v&nbsp;re\u00e1ln\u00e9m \u010dase pom\u00e1h\u00e1me odhalovat neefektivitu, p\u0159edch\u00e1zet poruch\u00e1m a&nbsp;zvy\u0161ovat provozn\u00ed v\u00fdkon. D\u00edky CaRES se va\u0161e data st\u00e1vaj\u00ed siln\u00fdm n\u00e1strojem pro vy\u0161\u0161\u00ed efektivitu a&nbsp;spolehlivost.[\/vc_column_text][vc_raw_html css=&#8220;&#8220;]PGEgaHJlZj0iaHR0cHM6Ly9jYXNhbGUuY2gvY3Mvc3RhaG5vdXQvIiBjbGFzcz0iYnRuX21haW4gcm9zc28iPgogICAgPGRpdj4KICAgICAgICA8c3Bhbj5TdMOhaG5vdXQ8c3ZnIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyIgd2lkdGg9IjE2IiBoZWlnaHQ9IjE2IiB2aWV3Ym94PSIwIDAgMTYgMTYiIGZpbGw9Im5vbmUiPgogICAgICAgICAgICAgICAgPHBhdGggZD0iTTguNzc3OTQgNEwxMi42NjY4IDhNMTIuNjY2OCA4TDguNzc3OTQgMTJNMTIuNjY2OCA4TDMuMzMzNSA4IiBzdHJva2U9IiMwMDVCOUUiIHN0cm9rZS13aWR0aD0iMS41IiBzdHJva2UtbGluZWNhcD0icm91bmQiIHN0cm9rZS1saW5lam9pbj0icm91bmQiPjwvcGF0aD4KICAgICAgICAgICAgPC9zdmc+PC9zcGFuPgogICAgICAgIDxzcGFuPlN0w6Fobm91dDxzdmcgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIiB3aWR0aD0iMTYiIGhlaWdodD0iMTYiIHZpZXdib3g9IjAgMCAxNiAxNiIgZmlsbD0ibm9uZSI+CiAgICAgICAgICAgICAgICA8cGF0aCBkPSJNOC43Nzc5NCA0TDEyLjY2NjggOE0xMi42NjY4IDhMOC43Nzc5NCAxMk0xMi42NjY4IDhMMy4zMzM1IDgiIHN0cm9rZT0iI2ZmZmZmZiIgc3Ryb2tlLXdpZHRoPSIxLjUiIHN0cm9rZS1saW5lY2FwPSJyb3VuZCIgc3Ryb2tlLWxpbmVqb2luPSJyb3VuZCI+PC9wYXRoPgogICAgICAgICAgICA8L3N2Zz48L3NwYW4+CiAgICA8L2Rpdj4KPC9hPg==[\/vc_raw_html][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;reverse sezione_servizio&#8220; id=&#8220;diagnostic_and_testing&#8220; disable_element=&#8220;yes&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;5\/12&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_raw_html css=&#8220;&#8220;]W3dwY29kZSBpZD0iNzg2MCIgdGFnX3NsdWc9InNlcnZpY2VzX2VuZ2luZWVyaW5nc2VydmljZXMiXQ==[\/vc_raw_html][image_with_animation image_url=&#8220;12131&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220;][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;7\/12&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][image_with_animation image_url=&#8220;2340&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;custom&#8220; max_width_custom=&#8220;60px&#8220;][nectar_highlighted_text color_type=&#8220;regular&#8220; text_color=&#8220;#cc0f4d&#8220; style=&#8220;full_text&#8220; highlight_expansion=&#8220;default&#8220; text_direction=&#8220;default&#8220;]\n<h2 class=\"big_h1\">Diagnostika a&nbsp;testov\u00e1n\u00ed<\/h2>\n[\/nectar_highlighted_text][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220; el_class=&#8220;descrizione&#8220;]\n<ul>\n<li>Metalurgick\u00e1 a&nbsp;chemick\u00e1 anal\u00fdza materi\u00e1l\u016f<\/li>\n<li>Kontrola mechanick\u00fdch vlastnost\u00ed<\/li>\n<li>Charakterizace katalyz\u00e1tor\u016f<\/li>\n<li>Anal\u00fdza koroze<\/li>\n<\/ul>\n[\/vc_column_text][vc_raw_html css=&#8220;&#8220;]PGEgaHJlZj0iaHR0cHM6Ly9jYXNhbGUuY2gvY3Mvc3RhaG5vdXQvIiBjbGFzcz0iYnRuX21haW4gcm9zc28iPgogICAgPGRpdj4KICAgICAgICA8c3Bhbj5TdMOhaG5vdXQ8c3ZnIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyIgd2lkdGg9IjE2IiBoZWlnaHQ9IjE2IiB2aWV3Ym94PSIwIDAgMTYgMTYiIGZpbGw9Im5vbmUiPgogICAgICAgICAgICAgICAgPHBhdGggZD0iTTguNzc3OTQgNEwxMi42NjY4IDhNMTIuNjY2OCA4TDguNzc3OTQgMTJNMTIuNjY2OCA4TDMuMzMzNSA4IiBzdHJva2U9IiMwMDVCOUUiIHN0cm9rZS13aWR0aD0iMS41IiBzdHJva2UtbGluZWNhcD0icm91bmQiIHN0cm9rZS1saW5lam9pbj0icm91bmQiPjwvcGF0aD4KICAgICAgICAgICAgPC9zdmc+PC9zcGFuPgogICAgICAgIDxzcGFuPlN0w6Fobm91dDxzdmcgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIiB3aWR0aD0iMTYiIGhlaWdodD0iMTYiIHZpZXdib3g9IjAgMCAxNiAxNiIgZmlsbD0ibm9uZSI+CiAgICAgICAgICAgICAgICA8cGF0aCBkPSJNOC43Nzc5NCA0TDEyLjY2NjggOE0xMi42NjY4IDhMOC43Nzc5NCAxMk0xMi42NjY4IDhMMy4zMzM1IDgiIHN0cm9rZT0iI2ZmZmZmZiIgc3Ryb2tlLXdpZHRoPSIxLjUiIHN0cm9rZS1saW5lY2FwPSJyb3VuZCIgc3Ryb2tlLWxpbmVqb2luPSJyb3VuZCI+PC9wYXRoPgogICAgICAgICAgICA8L3N2Zz48L3NwYW4+CiAgICA8L2Rpdj4KPC9hPg==[\/vc_raw_html][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;sezione_servizio&#8220; id=&#8220;digital_services&#8220; disable_element=&#8220;yes&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;5\/12&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_raw_html css=&#8220;&#8220;]W3dwY29kZSBpZD0iNzg2MCIgdGFnX3NsdWc9InNlcnZpY2VzX3BsYW50b3BlcmF0aW9uc2VydmljZXMiXQ==[\/vc_raw_html][image_with_animation image_url=&#8220;12131&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220;][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;7\/12&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][image_with_animation image_url=&#8220;2341&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;custom&#8220; max_width_custom=&#8220;60px&#8220;][nectar_highlighted_text color_type=&#8220;regular&#8220; text_color=&#8220;#cc0f4d&#8220; style=&#8220;full_text&#8220; highlight_expansion=&#8220;default&#8220; text_direction=&#8220;default&#8220;]\n<h2 class=\"big_h1\">Digit\u00e1ln\u00ed slu\u017eby<\/h2>\n[\/nectar_highlighted_text][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220; el_class=&#8220;descrizione&#8220;]<strong>CARES<\/strong>: Slu\u017eby projektov\u00e1n\u00ed na d\u00e1lku spole\u010dnosti Casale[\/vc_column_text][vc_raw_html css=&#8220;&#8220;]PGEgaHJlZj0iaHR0cHM6Ly9jYXNhbGUuY2gvY3Mvc3RhaG5vdXQvIiBjbGFzcz0iYnRuX21haW4gcm9zc28iPgogICAgPGRpdj4KICAgICAgICA8c3Bhbj5TdMOhaG5vdXQ8c3ZnIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyIgd2lkdGg9IjE2IiBoZWlnaHQ9IjE2IiB2aWV3Ym94PSIwIDAgMTYgMTYiIGZpbGw9Im5vbmUiPgogICAgICAgICAgICAgICAgPHBhdGggZD0iTTguNzc3OTQgNEwxMi42NjY4IDhNMTIuNjY2OCA4TDguNzc3OTQgMTJNMTIuNjY2OCA4TDMuMzMzNSA4IiBzdHJva2U9IiMwMDVCOUUiIHN0cm9rZS13aWR0aD0iMS41IiBzdHJva2UtbGluZWNhcD0icm91bmQiIHN0cm9rZS1saW5lam9pbj0icm91bmQiPjwvcGF0aD4KICAgICAgICAgICAgPC9zdmc+PC9zcGFuPgogICAgICAgIDxzcGFuPlN0w6Fobm91dDxzdmcgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIiB3aWR0aD0iMTYiIGhlaWdodD0iMTYiIHZpZXdib3g9IjAgMCAxNiAxNiIgZmlsbD0ibm9uZSI+CiAgICAgICAgICAgICAgICA8cGF0aCBkPSJNOC43Nzc5NCA0TDEyLjY2NjggOE0xMi42NjY4IDhMOC43Nzc5NCAxMk0xMi42NjY4IDhMMy4zMzM1IDgiIHN0cm9rZT0iI2ZmZmZmZiIgc3Ryb2tlLXdpZHRoPSIxLjUiIHN0cm9rZS1saW5lY2FwPSJyb3VuZCIgc3Ryb2tlLWxpbmVqb2luPSJyb3VuZCI+PC9wYXRoPgogICAgICAgICAgICA8L3N2Zz48L3NwYW4+CiAgICA8L2Rpdj4KPC9hPg==[\/vc_raw_html][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;reverse sezione_servizio&#8220; id=&#8220;machinery_services&#8220; disable_element=&#8220;yes&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;5\/12&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_raw_html css=&#8220;&#8220;]W3dwY29kZSBpZD0iNzg2MCIgdGFnX3NsdWc9InNlcnZpY2VzX3BsYW50b3BlcmF0aW9uc2VydmljZXMiXQ==[\/vc_raw_html][image_with_animation image_url=&#8220;12131&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220;][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;7\/12&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][image_with_animation image_url=&#8220;5479&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;custom&#8220; max_width_custom=&#8220;60px&#8220;][nectar_highlighted_text color_type=&#8220;regular&#8220; text_color=&#8220;#cc0f4d&#8220; style=&#8220;full_text&#8220; highlight_expansion=&#8220;default&#8220; text_direction=&#8220;default&#8220;]\n<h2 class=\"big_h1\">Stroj\u00edrensk\u00e9 slu\u017eby<\/h2>\n[\/nectar_highlighted_text][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220; el_class=&#8220;descrizione&#8220;]\n<ul>\n<li>Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.<\/li>\n<li>Duis aute irure dolor in reprehenderit in voluptate velit esse cillum dolore eu fugiat nulla pariatur.<\/li>\n<li>Excepteur sint occaecat cupidatat non proident, sunt in culpa qui officia deserunt mollit anim id est laborum.<\/li>\n<\/ul>\n[\/vc_column_text][vc_raw_html css=&#8220;&#8220;]PGEgaHJlZj0iaHR0cHM6Ly9jYXNhbGUuY2gvY3Mvc3RhaG5vdXQvIiBjbGFzcz0iYnRuX21haW4gcm9zc28iPgogICAgPGRpdj4KICAgICAgICA8c3Bhbj5TdMOhaG5vdXQ8c3ZnIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyIgd2lkdGg9IjE2IiBoZWlnaHQ9IjE2IiB2aWV3Ym94PSIwIDAgMTYgMTYiIGZpbGw9Im5vbmUiPgogICAgICAgICAgICAgICAgPHBhdGggZD0iTTguNzc3OTQgNEwxMi42NjY4IDhNMTIuNjY2OCA4TDguNzc3OTQgMTJNMTIuNjY2OCA4TDMuMzMzNSA4IiBzdHJva2U9IiMwMDVCOUUiIHN0cm9rZS13aWR0aD0iMS41IiBzdHJva2UtbGluZWNhcD0icm91bmQiIHN0cm9rZS1saW5lam9pbj0icm91bmQiPjwvcGF0aD4KICAgICAgICAgICAgPC9zdmc+PC9zcGFuPgogICAgICAgIDxzcGFuPlN0w6Fobm91dDxzdmcgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIiB3aWR0aD0iMTYiIGhlaWdodD0iMTYiIHZpZXdib3g9IjAgMCAxNiAxNiIgZmlsbD0ibm9uZSI+CiAgICAgICAgICAgICAgICA8cGF0aCBkPSJNOC43Nzc5NCA0TDEyLjY2NjggOE0xMi42NjY4IDhMOC43Nzc5NCAxMk0xMi42NjY4IDhMMy4zMzM1IDgiIHN0cm9rZT0iI2ZmZmZmZiIgc3Ryb2tlLXdpZHRoPSIxLjUiIHN0cm9rZS1saW5lY2FwPSJyb3VuZCIgc3Ryb2tlLWxpbmVqb2luPSJyb3VuZCI+PC9wYXRoPgogICAgICAgICAgICA8L3N2Zz48L3NwYW4+CiAgICA8L2Rpdj4KPC9hPg==[\/vc_raw_html][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_image=&#8220;2785&#8243; bg_position=&#8220;center center&#8220; background_image_loading=&#8220;default&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; bottom_margin=&#8220;20px&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;capabilities&#8220; id=&#8220;section_hero_categoria_primo&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":10,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-13838","page","type-page","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Slu\u017eby &#8226; Casale<\/title>\n<meta name=\"description\" content=\"A global supplier of integrated technologies, engineering &amp; construction solutions operating in the chemical industry since more than 100 years and with an unwavering commitment to contribute to a more sustainable and greener future.\" \/>\n<meta name=\"robots\" content=\"index, nofollow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casale.ch\/cs\/sluzby\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Slu\u017eby &#8226; Casale\" \/>\n<meta property=\"og:description\" content=\"A global supplier of integrated technologies, engineering &amp; construction solutions operating in the chemical industry since more than 100 years and with an unwavering commitment to contribute to a more sustainable and greener future.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casale.ch\/cs\/sluzby\/\" \/>\n<meta property=\"og:site_name\" content=\"Casale\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T14:37:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casale.ch\/wp-content\/uploads\/2024\/02\/casale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"712\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Odhadovan\u00e1 doba \u010dten\u00ed\" \/>\n\t<meta name=\"twitter:data1\" content=\"23 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casale.ch\/cs\/sluzby\/\",\"url\":\"https:\/\/casale.ch\/cs\/sluzby\/\",\"name\":\"Slu\u017eby &#8226; Casale\",\"isPartOf\":{\"@id\":\"https:\/\/casale.ch\/cs\/#website\"},\"datePublished\":\"2025-03-31T08:24:05+00:00\",\"dateModified\":\"2025-11-06T14:37:43+00:00\",\"description\":\"A global supplier of integrated technologies, engineering & construction solutions operating in the chemical industry since more than 100 years and with an unwavering commitment to contribute to a more sustainable and greener future.\",\"breadcrumb\":{\"@id\":\"https:\/\/casale.ch\/cs\/sluzby\/#breadcrumb\"},\"inLanguage\":\"cs\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casale.ch\/cs\/sluzby\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casale.ch\/cs\/sluzby\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/casale.ch\/cs\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Slu\u017eby\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casale.ch\/cs\/#website\",\"url\":\"https:\/\/casale.ch\/cs\/\",\"name\":\"Casale\",\"description\":\"Together for a new planet\",\"publisher\":{\"@id\":\"https:\/\/casale.ch\/cs\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casale.ch\/cs\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cs\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/casale.ch\/cs\/#organization\",\"name\":\"Casale\",\"url\":\"https:\/\/casale.ch\/cs\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\/\/casale.ch\/cs\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/casale.ch\/wp-content\/uploads\/2023\/08\/logo_casale.svg\",\"contentUrl\":\"https:\/\/casale.ch\/wp-content\/uploads\/2023\/08\/logo_casale.svg\",\"width\":1,\"height\":1,\"caption\":\"Casale\"},\"image\":{\"@id\":\"https:\/\/casale.ch\/cs\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Slu\u017eby &#8226; Casale","description":"A global supplier of integrated technologies, engineering & construction solutions operating in the chemical industry since more than 100 years and with an unwavering commitment to contribute to a more sustainable and greener future.","robots":{"index":"index","follow":"nofollow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casale.ch\/cs\/sluzby\/","og_locale":"cs_CZ","og_type":"article","og_title":"Slu\u017eby &#8226; Casale","og_description":"A global supplier of integrated technologies, engineering & construction solutions operating in the chemical industry since more than 100 years and with an unwavering commitment to contribute to a more sustainable and greener future.","og_url":"https:\/\/casale.ch\/cs\/sluzby\/","og_site_name":"Casale","article_modified_time":"2025-11-06T14:37:43+00:00","og_image":[{"width":1600,"height":712,"url":"https:\/\/casale.ch\/wp-content\/uploads\/2024\/02\/casale.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Odhadovan\u00e1 doba \u010dten\u00ed":"23 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/casale.ch\/cs\/sluzby\/","url":"https:\/\/casale.ch\/cs\/sluzby\/","name":"Slu\u017eby &#8226; Casale","isPartOf":{"@id":"https:\/\/casale.ch\/cs\/#website"},"datePublished":"2025-03-31T08:24:05+00:00","dateModified":"2025-11-06T14:37:43+00:00","description":"A global supplier of integrated technologies, engineering & construction solutions operating in the chemical industry since more than 100 years and with an unwavering commitment to contribute to a more sustainable and greener future.","breadcrumb":{"@id":"https:\/\/casale.ch\/cs\/sluzby\/#breadcrumb"},"inLanguage":"cs","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casale.ch\/cs\/sluzby\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/casale.ch\/cs\/sluzby\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casale.ch\/cs\/"},{"@type":"ListItem","position":2,"name":"Slu\u017eby"}]},{"@type":"WebSite","@id":"https:\/\/casale.ch\/cs\/#website","url":"https:\/\/casale.ch\/cs\/","name":"Casale","description":"Together for a new planet","publisher":{"@id":"https:\/\/casale.ch\/cs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casale.ch\/cs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cs"},{"@type":"Organization","@id":"https:\/\/casale.ch\/cs\/#organization","name":"Casale","url":"https:\/\/casale.ch\/cs\/","logo":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/casale.ch\/cs\/#\/schema\/logo\/image\/","url":"https:\/\/casale.ch\/wp-content\/uploads\/2023\/08\/logo_casale.svg","contentUrl":"https:\/\/casale.ch\/wp-content\/uploads\/2023\/08\/logo_casale.svg","width":1,"height":1,"caption":"Casale"},"image":{"@id":"https:\/\/casale.ch\/cs\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/casale.ch\/cs\/wp-json\/wp\/v2\/pages\/13838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casale.ch\/cs\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/casale.ch\/cs\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/casale.ch\/cs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/casale.ch\/cs\/wp-json\/wp\/v2\/comments?post=13838"}],"version-history":[{"count":6,"href":"https:\/\/casale.ch\/cs\/wp-json\/wp\/v2\/pages\/13838\/revisions"}],"predecessor-version":[{"id":13850,"href":"https:\/\/casale.ch\/cs\/wp-json\/wp\/v2\/pages\/13838\/revisions\/13850"}],"wp:attachment":[{"href":"https:\/\/casale.ch\/cs\/wp-json\/wp\/v2\/media?parent=13838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}