{"id":229,"count":49,"description":"","link":"https:\/\/casale.ch\/es\/category\/conferencias-es\/","name":"Conferencias","slug":"conferencias-es","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conferencias Archives &#8226; Casale<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conferencias Archives &#8226; Casale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casale.ch\/es\/category\/conferencias-es\/\" \/>\n<meta property=\"og:site_name\" content=\"Casale\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casale.ch\/wp-content\/uploads\/2024\/02\/casale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"712\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/casale.ch\\\/es\\\/category\\\/conferencias-es\\\/\",\"url\":\"https:\\\/\\\/casale.ch\\\/es\\\/category\\\/conferencias-es\\\/\",\"name\":\"Conferencias Archives &#8226; Casale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casale.ch\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casale.ch\\\/es\\\/category\\\/conferencias-es\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casale.ch\\\/es\\\/category\\\/conferencias-es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casale.ch\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conferencias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casale.ch\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/casale.ch\\\/es\\\/\",\"name\":\"Casale\",\"description\":\"Together for a new planet\",\"publisher\":{\"@id\":\"https:\\\/\\\/casale.ch\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casale.ch\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casale.ch\\\/es\\\/#organization\",\"name\":\"Casale\",\"url\":\"https:\\\/\\\/casale.ch\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casale.ch\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/casale.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo_casale.svg\",\"contentUrl\":\"https:\\\/\\\/casale.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo_casale.svg\",\"width\":1,\"height\":1,\"caption\":\"Casale\"},\"image\":{\"@id\":\"https:\\\/\\\/casale.ch\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conferencias Archives &#8226; Casale","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Conferencias Archives &#8226; Casale","og_url":"https:\/\/casale.ch\/es\/category\/conferencias-es\/","og_site_name":"Casale","og_image":[{"width":1600,"height":712,"url":"https:\/\/casale.ch\/wp-content\/uploads\/2024\/02\/casale.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/casale.ch\/es\/category\/conferencias-es\/","url":"https:\/\/casale.ch\/es\/category\/conferencias-es\/","name":"Conferencias Archives &#8226; Casale","isPartOf":{"@id":"https:\/\/casale.ch\/es\/#website"},"breadcrumb":{"@id":"https:\/\/casale.ch\/es\/category\/conferencias-es\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/casale.ch\/es\/category\/conferencias-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casale.ch\/es\/"},{"@type":"ListItem","position":2,"name":"Conferencias"}]},{"@type":"WebSite","@id":"https:\/\/casale.ch\/es\/#website","url":"https:\/\/casale.ch\/es\/","name":"Casale","description":"Together for a new planet","publisher":{"@id":"https:\/\/casale.ch\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casale.ch\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/casale.ch\/es\/#organization","name":"Casale","url":"https:\/\/casale.ch\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casale.ch\/es\/#\/schema\/logo\/image\/","url":"https:\/\/casale.ch\/wp-content\/uploads\/2023\/08\/logo_casale.svg","contentUrl":"https:\/\/casale.ch\/wp-content\/uploads\/2023\/08\/logo_casale.svg","width":1,"height":1,"caption":"Casale"},"image":{"@id":"https:\/\/casale.ch\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/casale.ch\/es\/wp-json\/wp\/v2\/categories\/229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casale.ch\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/casale.ch\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/casale.ch\/es\/wp-json\/wp\/v2\/posts?categories=229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}